{"id":37585,"date":"2024-05-13T13:45:34","date_gmt":"2024-05-13T11:45:34","guid":{"rendered":"https:\/\/www.mehrsichselbstsein-shop.de\/?post_type=product&#038;p=37585"},"modified":"2026-05-12T22:44:25","modified_gmt":"2026-05-12T20:44:25","slug":"logo-gross-shirt-light","status":"publish","type":"product","link":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/produkt\/logo-gross-shirt-light\/","title":{"rendered":"Logo gro\u00df &#8211; Shirt Light"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-38898\" src=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/5-3-1024x1024.png\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/5-3-1024x1024.png 1024w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/5-3-300x300.png 300w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/5-3-150x150.png 150w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/5-3-768x768.png 768w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/5-3-600x600.png 600w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/5-3-100x100.png 100w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/5-3.png 1080w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><img decoding=\"async\" class=\"aligncenter wp-image-38757\" src=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-2-1024x1024.png\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-2-1024x1024.png 1024w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-2-300x300.png 300w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-2-150x150.png 150w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-2-768x768.png 768w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-2-600x600.png 600w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-2-100x100.png 100w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-2.png 1080w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":35301,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[199],"product_tag":[],"class_list":{"0":"post-37585","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-t-shirt-logo","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable","13":"has-default-attributes"},"_links":{"self":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product\/37585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/comments?post=37585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/media\/35301"}],"wp:attachment":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/media?parent=37585"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product_brand?post=37585"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product_cat?post=37585"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product_tag?post=37585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}