{"id":34461,"date":"2024-05-02T15:59:54","date_gmt":"2024-05-02T13:59:54","guid":{"rendered":"https:\/\/www.mehrsichselbstsein-shop.de\/?post_type=product&#038;p=34461"},"modified":"2026-05-12T22:47:26","modified_gmt":"2026-05-12T20:47:26","slug":"logo-klein-shirt-women","status":"publish","type":"product","link":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/produkt\/logo-klein-shirt-women\/","title":{"rendered":"Logo klein &#8211; Shirt Women"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-34644\" src=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/4-1024x1024.png\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/4-1024x1024.png 1024w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/4-300x300.png 300w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/4-150x150.png 150w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/4-768x768.png 768w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/4-600x600.png 600w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/4-100x100.png 100w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/4.png 1080w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><img decoding=\"async\" class=\"aligncenter wp-image-34666\" src=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-1024x1024.png\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-1024x1024.png 1024w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-300x300.png 300w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-150x150.png 150w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-768x768.png 768w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-600x600.png 600w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1-100x100.png 100w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2024\/05\/1.png 1080w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":32603,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[199],"product_tag":[],"class_list":{"0":"post-34461","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-t-shirt-logo","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable","13":"has-default-attributes"},"_links":{"self":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product\/34461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/comments?post=34461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/media\/32603"}],"wp:attachment":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/media?parent=34461"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product_brand?post=34461"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product_cat?post=34461"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product_tag?post=34461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}