{"id":20729,"date":"2023-05-16T19:25:34","date_gmt":"2023-05-16T17:25:34","guid":{"rendered":"https:\/\/www.mehrsichselbstsein-shop.de\/produkt\/stella-collider-22\/"},"modified":"2026-05-12T22:45:29","modified_gmt":"2026-05-12T20:45:29","slug":"logo-gross-t-shirt-oversized-women","status":"publish","type":"product","link":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/produkt\/logo-gross-t-shirt-oversized-women\/","title":{"rendered":"Logo gro\u00df &#8211; T-Shirt Oversized &#8211; Women"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-24019\" src=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/T-Shirt-Oversize-Women-1-1024x1024.png\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/T-Shirt-Oversize-Women-1-1024x1024.png 1024w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/T-Shirt-Oversize-Women-1-300x300.png 300w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/T-Shirt-Oversize-Women-1-150x150.png 150w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/T-Shirt-Oversize-Women-1-768x768.png 768w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/T-Shirt-Oversize-Women-1-600x600.png 600w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/T-Shirt-Oversize-Women-1-100x100.png 100w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/T-Shirt-Oversize-Women-1.png 1080w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-24149\" src=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/MehrSichSelbstSein-1024x1024.png\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/MehrSichSelbstSein-1024x1024.png 1024w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/MehrSichSelbstSein-300x300.png 300w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/MehrSichSelbstSein-150x150.png 150w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/MehrSichSelbstSein-768x768.png 768w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/MehrSichSelbstSein-600x600.png 600w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/MehrSichSelbstSein-100x100.png 100w, https:\/\/www.mehrsichselbstsein-shop.de\/wp-content\/uploads\/2023\/05\/MehrSichSelbstSein.png 1080w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":15648,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[199],"product_tag":[],"class_list":{"0":"post-20729","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-t-shirt-logo","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable","13":"has-default-attributes"},"_links":{"self":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product\/20729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/comments?post=20729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/media\/15648"}],"wp:attachment":[{"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/media?parent=20729"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product_brand?post=20729"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product_cat?post=20729"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mehrsichselbstsein-shop.de\/en\/wp-json\/wp\/v2\/product_tag?post=20729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}